﻿{"id":1355,"date":"2018-09-27T10:11:53","date_gmt":"2018-09-27T08:11:53","guid":{"rendered":"http:\/\/www.benedettineitaliane.org\/newsletter\/?p=1355"},"modified":"2018-11-01T16:54:05","modified_gmt":"2018-11-01T15:54:05","slug":"newsletter-settembre-2018","status":"publish","type":"post","link":"https:\/\/www.benedettineitaliane.org\/newsletter\/2018\/09\/27\/newsletter-settembre-2018\/","title":{"rendered":"Newsletter \u2013 settembre 2018"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"text-align:center\">Chiese e mondo<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><strong><a href=\"http:\/\/www.ilregno.it\/regno-delle-donne\/blog\/di-fronte-alla-perversione-del-potere-stella-morra\" target=\"_blank\">Di fronte alla perversione del potere di Stella Morra<\/a><\/strong><\/p><\/p>\n\n\n\n<p style=\"text-align:left\">In dialogo con una riflessione di Marcello Neri a proposito degli abusi sessuali che, come ha scritto papa Francesco, sono sempre anche abusi di potere e di coscienza: forse la Chiesa pu\u00f2 uscire dall\u2019&#8221;incapacit\u00e0 paralizzante nel far fronte al proprio fallimento&#8221; ascoltando le voci e l\u2019esperienza delle donne.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/00.jpg\" alt=\"\" class=\"wp-image-1373\" width=\"468\" height=\"284\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/00.jpg 500w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/00-300x182.jpg 300w\" sizes=\"(max-width: 468px) 100vw, 468px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"http:\/\/www.cittadellaeditrice.com\/munera\/clericalismo\/\" target=\"_blank\"><strong>Clericalismo? di Ghislain Lafont<\/strong><\/a><\/p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"210\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/01.jpg\" alt=\"\" class=\"wp-image-1374\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/01.jpg 640w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/01-300x98.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"https:\/\/www.laciviltacattolica.it\/articolo\/fondamentalismo-evangelicale-e-integralismo-cattolico\/\" target=\"_blank\"><strong>Fondamentalismo evangelicale e integralismo cattolico. Un sorprendente ecumenismo di Antonio Spadaro &#8211; Marcelo Figueroa<\/strong><\/a><\/p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" loading=\"lazy\" width=\"520\" height=\"350\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/02.jpg\" alt=\"\" class=\"wp-image-1375\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/02.jpg 520w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/02-300x202.jpg 300w\" sizes=\"(max-width: 520px) 100vw, 520px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"https:\/\/www.monasterodibose.it\/comunita\/finestra-ecumenica\/11691-ecumenismo-tra-teologia-e-politica-negli-stati-uniti\" target=\"_blank\"><strong>Ecumenismo<\/strong> <strong>tra teologia e politica negli Stati Uniti di Massimo Faggioli<\/strong><\/a><\/p><\/p>\n\n\n\n<p>Il recente articolo pubblicato sulla rivista dei gesuiti Civilt\u00e0 Cattolica dal direttore, p. Antonio Spadaro SJ e dal teologo protestante argentino Marcelo Figueroa (dal giugno 2016 direttore dell\u2019edizione argentina de L\u2019Osservatore Romano) ha aperto un vivace e a tratti duro dibattito sul cattolicesimo negli Stati Uniti e su alcune caratteristiche dell\u2019ecumenismo politico della destra conservatrice in quel paese. L\u2019articolo definisce \u201cecumenismo dell\u2019odio\u201d quella cultura che negli Stati Uniti accomuna cristiani cattolici e protestanti, uniti da un\u2019avversione verso la modernit\u00e0 politica, il cosmopolitismo, i musulmani, e il dialogo interreligioso.<br>\nLa questione \u00e8 centrale per comprendere il cristianesimo nordamericano e gli USA in generale.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/03.jpg\" alt=\"\" class=\"wp-image-1376\" width=\"466\" height=\"303\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/03.jpg 755w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/03-300x195.jpg 300w\" sizes=\"(max-width: 466px) 100vw, 466px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"https:\/\/www.avvenire.it\/opinioni\/pagine\/mai-solo-per-s\" target=\"_blank\"><strong>Il mandato di Chiesa e Sinodo. Mai solo per s\u00e9 di Pierangelo Sequeri<\/strong><\/a><\/p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/04.jpg\" alt=\"\" class=\"wp-image-1383\" width=\"391\" height=\"260\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/04.jpg 600w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/04-300x200.jpg 300w\" sizes=\"(max-width: 391px) 100vw, 391px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"https:\/\/drive.google.com\/open?id=1C3f4RiiMHYpytoJmdnMBMSpSVmHMe0Rf\" target=\"_blank\"><strong>Il pollo e il Corvo di Aleberto Melloni<\/strong><\/a><\/p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/05.jpg\" alt=\"\" class=\"wp-image-1378\" width=\"392\" height=\"313\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/05.jpg 499w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/05-300x239.jpg 300w\" sizes=\"(max-width: 392px) 100vw, 392px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"http:\/\/www.doppiozero.com\/materiali\/lo-sguardo-del-migrante\" target=\"_blank\"><strong>Lo sguardo del migrante di Giampiero Frasca<\/strong><\/a><\/p><\/p>\n\n\n\n<p style=\"text-align:left\">Alcuni film sull&#8217;immigrazione<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/06.jpg\" alt=\"\" class=\"wp-image-1379\" width=\"439\" height=\"289\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/06.jpg 767w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/06-300x198.jpg 300w\" sizes=\"(max-width: 439px) 100vw, 439px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"http:\/\/www.doppiozero.com\/materiali\/gratuita-e-prendersi-cura\" target=\"_blank\"><strong>Gratuit\u00e0 e prendersi cura di Ugo Morelli<\/strong><\/a><\/p><\/p>\n\n\n\n<p style=\"text-align:left\">\u201cVivere un\u2019esistenza umana significa innanzitutto riceverla a partire da un riconoscimento che proviene dai propri coesistenti\u201d [Jean-Luc Nancy].<\/p>\n\n\n\n<p>Alcuni libri.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/07.jpg\" alt=\"\" class=\"wp-image-1380\" width=\"389\" height=\"232\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/07.jpg 1030w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/07-300x179.jpg 300w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/07-1024x611.jpg 1024w\" sizes=\"(max-width: 389px) 100vw, 389px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><strong><a href=\"https:\/\/www.la-croix.com\/Debats\/Forum-et-debats\/Il-faut-penser-lEglise-plusieurs-voix-2018-08-28-1200964449\" target=\"_blank\">Il faut penser l\u2019\u00c9glise \u00e0 plusieurs voix di Anne-Marie Pelletier<\/a><\/strong><\/p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/08.jpg\" alt=\"\" class=\"wp-image-1381\" width=\"400\" height=\"266\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/08.jpg 729w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/08-300x200.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"text-align:center\">Monachesimo<\/h2>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"http:\/\/www.laciviltacattolica.it\/articolo\/qual-e-il-compito-dei-cristiani-nella-societa-di-oggi\/\" target=\"_blank\"><strong>\u00abOpzione Benedetto\u00bb ed eresia donatista di Andreas Gon\u00e7alves Lind<\/strong><\/a><\/p><\/p>\n\n\n\n<p style=\"text-align:left\">Qual \u00e8 il compito dei cristiani nella societ\u00e0 di oggi?<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/09.jpg\" alt=\"\" class=\"wp-image-1384\" width=\"420\" height=\"279\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/09.jpg 2000w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/09-300x200.jpg 300w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/09-1024x682.jpg 1024w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"http:\/\/www.benedictines-cib.org\/\"><strong>8th International CIB Symposium, Rome<\/strong><\/a>,&nbsp;<a href=\"http:\/\/www.benedictines-cib.org\/\" target=\"_blank\"><strong>6 \u2013 13 September<\/strong>,<strong> 2018<\/strong><\/a><\/p><\/p>\n\n\n\n<p style=\"text-align:center\"><a href=\"https:\/\/www.flickr.com\/photos\/160874303@N06\/albums\" target=\"_blank\"><strong>Foto 1<\/strong><\/a><\/p>\n\n\n\n<p style=\"text-align:center\"><strong><a href=\"https:\/\/www.flickr.com\/photos\/anselmianum\/sets\/\" target=\"_blank\">Foto 2<\/a><\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/11.jpg\" alt=\"\" class=\"wp-image-1386\" width=\"480\" height=\"299\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/11.jpg 684w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/11-300x187.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\"><strong>_________________________________<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"https:\/\/www.monasterodibose.it\/fraternita\/civitella\/ospitalita-a-civitella\/incontri-attivita-civitella\" target=\"_blank\"><strong>&#8220;Dio nessuno lo ha mai visto&#8221;. Una guida al Vangelo di Giovanni di Marinella Perroni, teologa e biblista<\/strong><\/a><\/p><\/p>\n\n\n\n<p style=\"text-align:center\">Monastero di Civitella Incontri di autunno <br><br>sabato 6 &#8211; domenica 7 ottobre<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/12.jpg\" alt=\"\" class=\"wp-image-1387\" width=\"479\" height=\"270\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/12.jpg 998w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/12-300x169.jpg 300w\" sizes=\"(max-width: 479px) 100vw, 479px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"text-align:center\">Liturgia e sacramentaria<\/h2>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"http:\/\/www.cittadellaeditrice.com\/munera\/donne-e-ministeri-nella-chiesa-storia-di-un-pregiudizio-c-u-cortoni\/\" target=\"_blank\"><strong>Donne e ministeri nella chiesa: storia di un pregiudizio (C. U. Cortoni) di Andrea Grillo<\/strong><\/a><\/p><\/p>\n\n\n\n<p style=\"text-align:left\">Dopo il testo di Marinella Perroni, pubblicato con l\u2019ultimo post, un altro collega dell\u2019Ateneo S. Anselmo, Claudio U. Cortoni, reagisce, da storico, sul tema del rapporto tra donna e ministero ordinato. Si tratta di una ricca ricostruzione di \u201cpregiudizi\u201d che hanno profondamente segnato la storia della cultura europea, cristiana e cattolica. Credo che sia una lettura molto utile, per affrontare in modo corretto, e non ideologico, una questione, che in nessun modo pu\u00f2 essere considerate n\u00e9 chiusa, n\u00e9 sospesa o rimossa.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/10.jpg\" alt=\"\" class=\"wp-image-1388\" width=\"435\" height=\"366\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/10.jpg 960w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/10-300x253.jpg 300w\" sizes=\"(max-width: 435px) 100vw, 435px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n\n\n\n<p style=\"color:#ffffff;text-align:center\" class=\"has-text-color\">\n\n_________________________________\n\n<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-text-color has-background has-regular-font-size\"><p style=\"background-color:#f3f398;color:#2d05f8\" class=\"has-background has-regular-font-size\"><a href=\"https:\/\/alzogliocchiversoilcielo.blogspot.com\/2018\/08\/goffredo-boselli-lumanita-della-liturgia.html\" target=\"_blank\"><strong>L&#8217;umanit\u00e0 della liturgia di Goffredo Boselli<\/strong><\/a> <\/p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"http:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/13.jpg\" alt=\"\" class=\"wp-image-1389\" width=\"455\" height=\"254\" srcset=\"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/13.jpg 625w, https:\/\/www.benedettineitaliane.org\/newsletter\/wp-content\/uploads\/2018\/09\/13-300x168.jpg 300w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/figure><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-regular-font-size has-luminous-vivid-orange-color\"><p style=\"text-align:center\" class=\"has-regular-font-size has-luminous-vivid-orange-color\">_________________________________<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chiese e mondo Di fronte alla perversione del potere di Stella Morra In dialogo con una riflessione di Marcello Neri a proposito degli abusi sessuali che, come ha scritto papa Francesco, sono sempre anche abusi di potere e di coscienza: forse la Chiesa pu\u00f2 uscire dall\u2019&#8221;incapacit\u00e0 paralizzante nel far fronte al proprio fallimento&#8221; ascoltando le &hellip; <a href=\"https:\/\/www.benedettineitaliane.org\/newsletter\/2018\/09\/27\/newsletter-settembre-2018\/\" class=\"more-link\">Continua a leggere <span class=\"screen-reader-text\">Newsletter \u2013 settembre 2018<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/posts\/1355"}],"collection":[{"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/comments?post=1355"}],"version-history":[{"count":27,"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/posts\/1355\/revisions"}],"predecessor-version":[{"id":1429,"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/posts\/1355\/revisions\/1429"}],"wp:attachment":[{"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/media?parent=1355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/categories?post=1355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.benedettineitaliane.org\/newsletter\/wp-json\/wp\/v2\/tags?post=1355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}